{"id":1097,"date":"2018-04-04T12:02:56","date_gmt":"2018-04-04T10:02:56","guid":{"rendered":"https:\/\/www.primaxbuild.it\/wp-content\/uploads\/2017\/12\/primacrete.png"},"modified":"2018-04-04T12:02:56","modified_gmt":"2018-04-04T10:02:56","slug":"primacrete-2-2","status":"inherit","type":"attachment","link":"https:\/\/www.primaxbuild.it\/en\/?attachment_id=1097","title":{"rendered":"primacrete"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-1097","attachment","type-attachment","status-inherit","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>primacrete - Primax<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.primaxbuild.it\/wp-content\/uploads\/2017\/12\/primacrete.png\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"primacrete - Primax\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.primaxbuild.it\/wp-content\/uploads\/2017\/12\/primacrete.png\" \/>\n<meta property=\"og:site_name\" content=\"Primax\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.primaxbuild.it\/wp-content\/uploads\/2017\/12\/primacrete.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.primaxbuild.it\/wp-content\/uploads\/2017\/12\/primacrete.png\",\"url\":\"https:\/\/www.primaxbuild.it\/wp-content\/uploads\/2017\/12\/primacrete.png\",\"name\":\"primacrete - Primax\",\"isPartOf\":{\"@id\":\"https:\/\/www.primaxbuild.it\/#website\"},\"datePublished\":\"2018-04-04T10:02:56+00:00\",\"dateModified\":\"2018-04-04T10:02:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.primaxbuild.it\/wp-content\/uploads\/2017\/12\/primacrete.png#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.primaxbuild.it\/wp-content\/uploads\/2017\/12\/primacrete.png\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.primaxbuild.it\/wp-content\/uploads\/2017\/12\/primacrete.png#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.primaxbuild.it\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PRIMACRETE\",\"item\":\"https:\/\/www.primaxbuild.it\/en\/prodotti\/lattex\/primacrete\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"primacrete\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.primaxbuild.it\/#website\",\"url\":\"https:\/\/www.primaxbuild.it\/\",\"name\":\"Primax\",\"description\":\"The most complete range for building\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.primaxbuild.it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"primacrete - Primax","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.primaxbuild.it\/wp-content\/uploads\/2017\/12\/primacrete.png","og_locale":"en_US","og_type":"article","og_title":"primacrete - Primax","og_url":"https:\/\/www.primaxbuild.it\/wp-content\/uploads\/2017\/12\/primacrete.png","og_site_name":"Primax","og_image":[{"width":800,"height":800,"url":"https:\/\/www.primaxbuild.it\/wp-content\/uploads\/2017\/12\/primacrete.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.primaxbuild.it\/wp-content\/uploads\/2017\/12\/primacrete.png","url":"https:\/\/www.primaxbuild.it\/wp-content\/uploads\/2017\/12\/primacrete.png","name":"primacrete - Primax","isPartOf":{"@id":"https:\/\/www.primaxbuild.it\/#website"},"datePublished":"2018-04-04T10:02:56+00:00","dateModified":"2018-04-04T10:02:56+00:00","breadcrumb":{"@id":"https:\/\/www.primaxbuild.it\/wp-content\/uploads\/2017\/12\/primacrete.png#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.primaxbuild.it\/wp-content\/uploads\/2017\/12\/primacrete.png"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.primaxbuild.it\/wp-content\/uploads\/2017\/12\/primacrete.png#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.primaxbuild.it\/en\/"},{"@type":"ListItem","position":2,"name":"PRIMACRETE","item":"https:\/\/www.primaxbuild.it\/en\/prodotti\/lattex\/primacrete\/"},{"@type":"ListItem","position":3,"name":"primacrete"}]},{"@type":"WebSite","@id":"https:\/\/www.primaxbuild.it\/#website","url":"https:\/\/www.primaxbuild.it\/","name":"Primax","description":"The most complete range for building","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.primaxbuild.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.primaxbuild.it\/wp-content\/uploads\/2017\/12\/primacrete.png'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.primaxbuild.it\/wp-content\/uploads\/2017\/12\/primacrete-300x300.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.primaxbuild.it\/wp-content\/uploads\/2017\/12\/primacrete-300x300.png 300w, https:\/\/www.primaxbuild.it\/wp-content\/uploads\/2017\/12\/primacrete-150x150.png 150w, https:\/\/www.primaxbuild.it\/wp-content\/uploads\/2017\/12\/primacrete-768x768.png 768w, https:\/\/www.primaxbuild.it\/wp-content\/uploads\/2017\/12\/primacrete-500x500.png 500w, https:\/\/www.primaxbuild.it\/wp-content\/uploads\/2017\/12\/primacrete-100x100.png 100w, https:\/\/www.primaxbuild.it\/wp-content\/uploads\/2017\/12\/primacrete-266x266.png 266w, https:\/\/www.primaxbuild.it\/wp-content\/uploads\/2017\/12\/primacrete-1000x1000.png 1000w, https:\/\/www.primaxbuild.it\/wp-content\/uploads\/2017\/12\/primacrete.png 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" itemprop=\"image\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/png","media_details":{"width":800,"height":800,"file":"2017\/12\/primacrete.png","sizes":{"thumbnail":{"file":"primacrete-150x150.png","width":150,"height":150,"mime_type":"image\/png","source_url":"https:\/\/www.primaxbuild.it\/wp-content\/uploads\/2017\/12\/primacrete-150x150.png"},"medium":{"file":"primacrete-300x300.png","width":300,"height":300,"mime_type":"image\/png","source_url":"https:\/\/www.primaxbuild.it\/wp-content\/uploads\/2017\/12\/primacrete-300x300.png"},"medium_large":{"file":"primacrete-768x768.png","width":768,"height":768,"mime_type":"image\/png","source_url":"https:\/\/www.primaxbuild.it\/wp-content\/uploads\/2017\/12\/primacrete-768x768.png"},"woocommerce_thumbnail":{"file":"primacrete-500x500.png","width":500,"height":500,"uncropped":true,"mime_type":"image\/png","source_url":"https:\/\/www.primaxbuild.it\/wp-content\/uploads\/2017\/12\/primacrete-500x500.png"},"woocommerce_gallery_thumbnail":{"file":"primacrete-100x100.png","width":100,"height":100,"mime_type":"image\/png","source_url":"https:\/\/www.primaxbuild.it\/wp-content\/uploads\/2017\/12\/primacrete-100x100.png"},"shop_catalog":{"file":"primacrete-500x500.png","width":500,"height":500,"mime_type":"image\/png","source_url":"https:\/\/www.primaxbuild.it\/wp-content\/uploads\/2017\/12\/primacrete-500x500.png"},"shop_thumbnail":{"file":"primacrete-100x100.png","width":100,"height":100,"mime_type":"image\/png","source_url":"https:\/\/www.primaxbuild.it\/wp-content\/uploads\/2017\/12\/primacrete-100x100.png"},"266x266":{"file":"primacrete-266x266.png","width":266,"height":266,"mime_type":"image\/png","source_url":"https:\/\/www.primaxbuild.it\/wp-content\/uploads\/2017\/12\/primacrete-266x266.png"},"woocommerce-recent-carousel":{"file":"primacrete-330x260.png","width":330,"height":260,"width_query":330,"height_query":260,"mime_type":"image\/png","source_url":"https:\/\/www.primaxbuild.it\/wp-content\/uploads\/2017\/12\/primacrete-330x260.png"},"woocommerce_single":{"file":"primacrete-1000x1000.png","width":1000,"height":1000,"filesize":622539,"width_query":1000,"height_query":0,"mime_type":"image\/png","source_url":"https:\/\/www.primaxbuild.it\/wp-content\/uploads\/2017\/12\/primacrete-1000x1000.png"},"600x99999":{"file":"primacrete-600x800.png","width":600,"height":800,"filesize":453175,"mime_type":"image\/png","source_url":"https:\/\/www.primaxbuild.it\/wp-content\/uploads\/2017\/12\/primacrete-600x800.png"},"full":{"file":"primacrete.png","width":800,"height":800,"mime_type":"image\/png","source_url":"https:\/\/www.primaxbuild.it\/wp-content\/uploads\/2017\/12\/primacrete.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":270,"source_url":"https:\/\/www.primaxbuild.it\/wp-content\/uploads\/2017\/12\/primacrete.png","_links":{"self":[{"href":"https:\/\/www.primaxbuild.it\/en\/wp-json\/wp\/v2\/media\/1097","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.primaxbuild.it\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.primaxbuild.it\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.primaxbuild.it\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.primaxbuild.it\/en\/wp-json\/wp\/v2\/comments?post=1097"}]}}